{"id":23302,"date":"2024-04-22T04:14:41","date_gmt":"2024-04-22T04:14:41","guid":{"rendered":"https:\/\/petradraskovic.com\/vaza\/"},"modified":"2024-04-22T04:14:41","modified_gmt":"2024-04-22T04:14:41","slug":"vaza","status":"publish","type":"page","link":"https:\/\/petradraskovic.com\/sl\/vaza\/","title":{"rendered":"Vaza"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23302\" class=\"elementor elementor-23302 elementor-21927\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fad8bd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fad8bd1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd0211d\" data-id=\"bd0211d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5473dd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f5473dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a47f06\" data-id=\"8a47f06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfda1f4 elementor-widget elementor-widget-image\" data-id=\"dfda1f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg\" class=\"attachment-large size-large wp-image-21864\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss.jpg 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-07c406a\" data-id=\"07c406a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-296ce1e elementor-widget elementor-widget-image\" data-id=\"296ce1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss.jpg\" class=\"attachment-full size-full wp-image-21870\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss.jpg 2048w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-800x533.jpg 800w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-88c4fd4\" data-id=\"88c4fd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2f65ca elementor-widget elementor-widget-image\" data-id=\"f2f65ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1024x683.jpg\" class=\"attachment-large size-large wp-image-21874\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss.jpg 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec3574e elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"ec3574e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fc24d5b\" data-id=\"fc24d5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-934e1d1 elementor-widget elementor-widget-image\" data-id=\"934e1d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W.jpg\" class=\"attachment-full size-full wp-image-21150\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W.jpg 1365w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-400x600.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-600x900.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-200x300.jpg 200w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-683x1024.jpg 683w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-768x1152.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-1024x1536.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_7207_DxO_PDP_W-800x1200.jpg 800w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12a7394\" data-id=\"12a7394\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3742521 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"3742521\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1152\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-768x1152.jpg\" class=\"attachment-medium_large size-medium_large wp-image-23229\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-768x1152.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-200x300.jpg 200w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-683x1024.jpg 683w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-1024x1536.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-800x1200.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-400x600.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB-600x900.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2024\/04\/ARS_2981_A-WEB.jpg 1365w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>#black\/white - earth vase<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-58b7778\" data-id=\"58b7778\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f89a7b0 elementor-widget elementor-widget-image\" data-id=\"f89a7b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1498\" height=\"2048\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_.jpg\" class=\"attachment-full size-full wp-image-20955\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_.jpg 1498w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-400x547.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-600x820.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-219x300.jpg 219w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-749x1024.jpg 749w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-768x1050.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-1124x1536.jpg 1124w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-1400x1914.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/07\/ARS_2715_PDP_-800x1094.jpg 800w\" sizes=\"(max-width: 1498px) 100vw, 1498px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e63046c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e63046c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b3dea8f\" data-id=\"b3dea8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbf09fd elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"bbf09fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"588\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-768x588.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21862\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-768x588.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-400x306.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-600x459.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-300x230.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-1024x784.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-1536x1175.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-1400x1071.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss-800x612.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4859_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>#black\/white - earth vase<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9898592\" data-id=\"9898592\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61f0f64 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"61f0f64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21942\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/001_ARS_4864_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>#green\/pink  vase<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fd1e9c0\" data-id=\"fd1e9c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceff98a elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ceff98a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"578\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-768x578.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21815\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-768x578.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-400x301.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-600x451.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-300x226.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-1024x770.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-1536x1155.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-1400x1053.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss-800x602.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/6_ARS_4836_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p><span style=\"font-family: jost, Helvetica, Arial, sans-serif;font-size: 16px;font-style: normal;font-weight: 400\">#small bowl set of 6 - 3<\/span><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-062f032 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"062f032\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-575994c\" data-id=\"575994c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f00165 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"7f00165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21874\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4891_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>#small vase - rustic - 1<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b10f373\" data-id=\"b10f373\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d27794 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"6d27794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21937\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/ARS_4887_01_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p><span style=\"font-family: jost, Helvetica, Arial, sans-serif;font-size: 16px;font-style: normal;font-weight: 400\">#vase - rustic - 2<\/span><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-49d18f2\" data-id=\"49d18f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6960c49 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"6960c49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21870\" alt=\"\" srcset=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-768x512.jpg 768w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-400x267.jpg 400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-600x400.jpg 600w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-300x200.jpg 300w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1024x683.jpg 1024w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1536x1024.jpg 1536w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-1400x933.jpg 1400w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss-800x533.jpg 800w, https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4885_PDP_ss.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p><span style=\"font-family: jost, Helvetica, Arial, sans-serif;font-size: 16px;font-style: normal;font-weight: 400\">#vase - rustic - 3<\/span><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tEUR\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>#black\/white \u2013 earth vase EUR #black\/white \u2013 earth vase EUR #green\/pink vase EUR #small bowl set of 6 \u2013 3 EUR #small vase \u2013 rustic \u2013 1 EUR #vase \u2013 rustic \u2013 2 EUR #vase \u2013 rustic \u2013 3 EUR<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-23302","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vaza - PETRA DRA\u0160KOVI\u010c PELC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/petradraskovic.com\/sl\/vaza\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaza - PETRA DRA\u0160KOVI\u010c PELC\" \/>\n<meta property=\"og:description\" content=\"#black\/white \u2013 earth vase EUR #black\/white \u2013 earth vase EUR #green\/pink vase EUR #small bowl set of 6 \u2013 3 EUR #small vase \u2013 rustic \u2013 1 EUR #vase \u2013 rustic \u2013 2 EUR #vase \u2013 rustic \u2013 3 EUR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/petradraskovic.com\/sl\/vaza\/\" \/>\n<meta property=\"og:site_name\" content=\"PETRA DRA\u0160KOVI\u010c PELC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/petra.draskovic.1\" \/>\n<meta property=\"og:image\" content=\"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/\",\"url\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/\",\"name\":\"Vaza - PETRA DRA\u0160KOVI\u010c PELC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/petradraskovic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/01_ARS_4861_PDP_a_ss-1024x683.jpg\",\"datePublished\":\"2024-04-22T04:14:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/petradraskovic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/01_ARS_4861_PDP_a_ss-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/petradraskovic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/01_ARS_4861_PDP_a_ss-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/vaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#website\",\"url\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/\",\"name\":\"PETRA DRA\u0160KOVI\u010c PELC\",\"description\":\"EXPLORE. INSPIRE. CARE\",\"publisher\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#organization\",\"name\":\"Petra Dra\u0161kovi\u010d Pelc\",\"url\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/petradraskovic.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/EXPLORE-INSPIRE-CARE-WWW-pine.png\",\"contentUrl\":\"https:\\\/\\\/petradraskovic.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/EXPLORE-INSPIRE-CARE-WWW-pine.png\",\"width\":2710,\"height\":570,\"caption\":\"Petra Dra\u0161kovi\u010d Pelc\"},\"image\":{\"@id\":\"https:\\\/\\\/petradraskovic.com\\\/sl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/petra.draskovic.1\",\"https:\\\/\\\/www.instagram.com\\\/petra_draskovic_pelc\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/petra-draskovic-pelc-5672125\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vaza - PETRA DRA\u0160KOVI\u010c PELC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/petradraskovic.com\/sl\/vaza\/","og_locale":"sl_SI","og_type":"article","og_title":"Vaza - PETRA DRA\u0160KOVI\u010c PELC","og_description":"#black\/white \u2013 earth vase EUR #black\/white \u2013 earth vase EUR #green\/pink vase EUR #small bowl set of 6 \u2013 3 EUR #small vase \u2013 rustic \u2013 1 EUR #vase \u2013 rustic \u2013 2 EUR #vase \u2013 rustic \u2013 3 EUR","og_url":"https:\/\/petradraskovic.com\/sl\/vaza\/","og_site_name":"PETRA DRA\u0160KOVI\u010c PELC","article_publisher":"https:\/\/www.facebook.com\/petra.draskovic.1","og_image":[{"url":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/petradraskovic.com\/sl\/vaza\/","url":"https:\/\/petradraskovic.com\/sl\/vaza\/","name":"Vaza - PETRA DRA\u0160KOVI\u010c PELC","isPartOf":{"@id":"https:\/\/petradraskovic.com\/sl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/petradraskovic.com\/sl\/vaza\/#primaryimage"},"image":{"@id":"https:\/\/petradraskovic.com\/sl\/vaza\/#primaryimage"},"thumbnailUrl":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg","datePublished":"2024-04-22T04:14:41+00:00","breadcrumb":{"@id":"https:\/\/petradraskovic.com\/sl\/vaza\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/petradraskovic.com\/sl\/vaza\/"]}]},{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/petradraskovic.com\/sl\/vaza\/#primaryimage","url":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg","contentUrl":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2023\/08\/01_ARS_4861_PDP_a_ss-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/petradraskovic.com\/sl\/vaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/petradraskovic.com\/sl\/"},{"@type":"ListItem","position":2,"name":"Vaza"}]},{"@type":"WebSite","@id":"https:\/\/petradraskovic.com\/sl\/#website","url":"https:\/\/petradraskovic.com\/sl\/","name":"PETRA DRA\u0160KOVI\u010c PELC","description":"EXPLORE. INSPIRE. CARE","publisher":{"@id":"https:\/\/petradraskovic.com\/sl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/petradraskovic.com\/sl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"},{"@type":"Organization","@id":"https:\/\/petradraskovic.com\/sl\/#organization","name":"Petra Dra\u0161kovi\u010d Pelc","url":"https:\/\/petradraskovic.com\/sl\/","logo":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/petradraskovic.com\/sl\/#\/schema\/logo\/image\/","url":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2020\/04\/EXPLORE-INSPIRE-CARE-WWW-pine.png","contentUrl":"https:\/\/petradraskovic.com\/wp-content\/uploads\/2020\/04\/EXPLORE-INSPIRE-CARE-WWW-pine.png","width":2710,"height":570,"caption":"Petra Dra\u0161kovi\u010d Pelc"},"image":{"@id":"https:\/\/petradraskovic.com\/sl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/petra.draskovic.1","https:\/\/www.instagram.com\/petra_draskovic_pelc\/","https:\/\/www.linkedin.com\/in\/petra-draskovic-pelc-5672125\/"]}]}},"_links":{"self":[{"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/pages\/23302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/comments?post=23302"}],"version-history":[{"count":1,"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/pages\/23302\/revisions"}],"predecessor-version":[{"id":23306,"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/pages\/23302\/revisions\/23306"}],"wp:attachment":[{"href":"https:\/\/petradraskovic.com\/sl\/wp-json\/wp\/v2\/media?parent=23302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}